{"id":16909,"date":"2022-05-03T06:42:10","date_gmt":"2022-05-03T06:42:10","guid":{"rendered":"https:\/\/www.moltexbaby.com\/?p=16909"},"modified":"2022-05-03T06:45:23","modified_gmt":"2022-05-03T06:45:23","slug":"que-hacer-si-mi-bebe-no-quiere-beber-leche","status":"publish","type":"post","link":"https:\/\/www.moltexbaby.com\/es\/tu-peque-y-tu\/alimentacion-es\/que-hacer-si-mi-bebe-no-quiere-beber-leche\/","title":{"rendered":"\u00bfQu\u00e9 hacer si mi beb\u00e9 no quiere beber leche?"},"content":{"rendered":"<p><strong>Todos los beb\u00e9s toman sin problemas la leche materna o de f\u00f3rmula en sus primeros meses de vida. Pero al cumplir los 12 meses y pasar a beber leche de vaca normal en vaso, muchos se niega o la rechazan\u2026 \u00bfqu\u00e9 hacer en estos casos?<\/strong><\/p>\n<p><strong>\u00bfEs malo que no beba leche?<\/strong><\/p>\n<p>La leche es uno de los alimentos b\u00e1sicos de una dieta saludable ya que aporta al beb\u00e9 hidratos de carbono, principalmente lactosa, grasas, prote\u00ednas, minerales como calcio, f\u00f3sforo, magnesio, potasio y zinc, y vitaminas como B1, B2, B3, B9, A, D.<\/p>\n<p>En especial, la leche es uno de los principales aportes de calcio, un mineral imprescindible para<a href=\"https:\/\/www.moltexbaby.com\/es\/tu-peque-y-tu\/curiosidades\/es-cierto-que-los-bebes-tienen-mas-huesos-que-los-adultos\/\"> la salud \u00f3sea<\/a> y el crecimiento de los huesos. Cumplidos los 12 meses, el beb\u00e9 necesita un aporte diario de 800 mg de calcio para el crecimiento y la osificaci\u00f3n de su esqueleto. Adem\u00e1s, el calcio es imprescindible para otras muchas funciones como la coagulaci\u00f3n de la sangre, la contracci\u00f3n de los m\u00fasculos y la transmisi\u00f3n de impulsos nerviosos. Por eso, cuando un beb\u00e9 se niega a beber leche, los padres se preocupan ya que saben que necesitan leche para una dieta saludable. Sin embargo, no hay que asustarse ya que, aunque la leche es uno de los principales alimentos que aportan calcio, hay otros que pueden ayudar a completar las necesidades diarias de los ni\u00f1os.<\/p>\n<p><strong>\u00bfPor qu\u00e9 mi beb\u00e9 no quiere beber leche?<\/strong><\/p>\n<p><strong>1- No le gusta el sabor<\/strong>. El sabor de la leche de vaca normal es diferente de la leche de f\u00f3rmula o de la leche materna que han estado bebiendo hasta ahora, por lo que es posible que la rechace porque le sabe m\u00e1s fuerte y no le agrada.<\/p>\n<p><strong>2- Tiene intolerancia a la lactosa<\/strong>. En el caso de los intolerantes a la lactosa, en cuanto beben leche notan hinchaz\u00f3n, gases y dolor abdominal, por lo que es normal que no quieran beber leche ya que<a href=\"https:\/\/www.moltexbaby.com\/es\/tu-peque-y-tu\/alimentacion-es\/por-que-los-bebes-vomitan-la-leche\/\"> les sienta mal.<\/a><\/p>\n<p><strong>\u00bfQu\u00e9 otros alimentos tienen calcio?<\/strong><\/p>\n<p>Como dec\u00edamos, existen otros muchos alimentos que son fuente de calcio, por lo que, si tu hijo no quiere beber leche, puedes aumentar el consumo de estos en su alimentaci\u00f3n diaria para completar su nutrici\u00f3n:<\/p>\n<p>&#8211; otros l\u00e1cteos, como yogures y queso.<\/p>\n<p>&#8211; pescados azules como la sardina o el boquer\u00f3n<\/p>\n<p>&#8211; yema de huevo<\/p>\n<p>&#8211; legumbres<\/p>\n<p>&#8211; verduras de hoja verde como acelgas, espinacas o br\u00f3coli<\/p>\n<p>&#8211; cereales como avena o trigo<\/p>\n<p>&#8211; alimentos fortificados<\/p>\n<p><strong>\u00bfC\u00f3mo conseguir que beba leche?<\/strong><\/p>\n<p>A pesar de que puede adquirir el calcio necesario de otros alimentos, es conveniente no renunciar a la leche y probar estos consejos para conseguir que beba al menos un vasito de leche todos los d\u00edas en el desayuno:<\/p>\n<ol>\n<li>A\u00f1ade a la leche cacao en polvo para que tenga un sabor m\u00e1s agradable.<\/li>\n<li>Prueba las leches de crecimiento, para ni\u00f1os de 1 a 3 a\u00f1os. Estas leches tienen un sabor m\u00e1s similar a la leche de f\u00f3rmula de continuaci\u00f3n, por lo que le resultar\u00e1 m\u00e1s agradable.<\/li>\n<li>Si tiene intolerancia a la lactosa, opta por leches sin lactosa.<\/li>\n<li>Prueba las leches vegetales, como<a href=\"https:\/\/www.moltexbaby.com\/es\/tu-peque-y-tu\/alimentacion-es\/puedo-dar-leche-de-almendras-a-mi-bebe\/\"> la leche de almendras<\/a>, la de avena, la de arroz o la de soja\u2026 enriquecidas con calcio, ya que no todas aportan calcio en la misma cantidad.<\/li>\n<li>A\u00f1ade cereales a la leche.<\/li>\n<li>Haz batidos naturales con leche y trozos de pl\u00e1tano, fresa, pera, etc.<\/li>\n<li>Ofr\u00e9cele m\u00e1s l\u00e1cteos como yogures naturales, yogur l\u00edquido, queso semidesnatado de fresco, etc.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La leche es uno de los principales aportes de calcio. Por eso, cuando un beb\u00e9 se niega a beber leche, los padres se preocupan ya que saben que necesitan leche para una dieta saludable.<\/p>\n","protected":false},"author":20,"featured_media":16910,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1843],"tags":[],"class_list":["post-16909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacion-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/posts\/16909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/comments?post=16909"}],"version-history":[{"count":0,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/posts\/16909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/media\/16910"}],"wp:attachment":[{"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/media?parent=16909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/categories?post=16909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moltexbaby.com\/es\/wp-json\/wp\/v2\/tags?post=16909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}